{"id":4438,"date":"2013-02-19T00:00:00","date_gmt":"2013-02-19T05:00:00","guid":{"rendered":"https:\/\/catalyst.org\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/"},"modified":"2023-04-13T12:44:29","modified_gmt":"2023-04-13T16:44:29","slug":"enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500","status":"publish","type":"research_element","link":"https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/","title":{"rendered":"Enqu\u00eate Catalyst 2012 : Les femmes cadres sup\u00e9rieures et les femmes les mieux r\u00e9mun\u00e9r\u00e9es selon le classement Financial Post 500 (Rapport)"},"content":{"rendered":"<p>Ce rapport compte :<\/p>\n<ul>\n<li>La proportion de femmes dans tous les postes de cadres sup\u00e9rieurs.<\/li>\n<li>La proportion de femmes cadres sup\u00e9rieures et de femmes les mieux r\u00e9mun\u00e9r\u00e9es dans les soci\u00e9t\u00e9s ouvertes.<\/li>\n<li>Toutes les soci\u00e9t\u00e9s et toutes les soci\u00e9t\u00e9s publiques comptant 0 pour cent, 25 pour cent et plus, et 40 pour cent et plus de femmes cadres sup\u00e9rieures.<\/li>\n<li>La proportion de femmes occupant des postes de cadres sup\u00e9rieurs dans les soci\u00e9t\u00e9s ouvertes, les soci\u00e9t\u00e9s priv\u00e9es, les soci\u00e9t\u00e9s de la couronne et les coop\u00e9ratives.<\/li>\n<\/ul>\n<div>\n<p>Les annexes fournissent des points de comparaison additionnels par r\u00e9gion et industrie ainsi qu&#8217;une liste de soci\u00e9t\u00e9s comptant la repr\u00e9sentation la plus \u00e9lev\u00e9e et la plus faible de femmes cadres sup\u00e9rieures.<\/p>\n<ul>\n<li>En 2012, les femmes d\u00e9tenaient 18,1 pour cent des postes de cadres sup\u00e9rieurs dans les soci\u00e9t\u00e9s du classement <em>Financial Post<\/em> 500 et 6,9 pour cent des postes les mieux r\u00e9mun\u00e9r\u00e9s dans les soci\u00e9t\u00e9s ouvertes.<\/li>\n<li>En 2010 et en 2012, environ un tiers de toutes les soci\u00e9t\u00e9s comptaient 25 pour cent et plus de femmes cadres sup\u00e9rieures, tandis qu&#8217;une proportion quasi identique ne comptait aucune femme cadre sup\u00e9rieure.<\/li>\n<\/ul>\n<div>\n<h4>Annexes<\/h4>\n<ul>\n<li><a href=\"\/knowledge\/enquete-catalyst-2012-Annexe-1-Methodologie\"><em>Annexe 1\u2014M\u00e9thodologie<\/em><\/a><\/li>\n<li><a href=\"\/knowledge\/enquete-catalyst-2012-annexe-2-societes-comptant-25-ou-plus-de-femmes-cadres-superieures\"><em>Annexe 2\u2014Soci\u00e9t\u00e9s comptant 25 % ou plus de femmes cadres sup\u00e9rieures<\/em><\/a><\/li>\n<li><a href=\"\/knowledge\/enquete-catalyst-2012-annexe-3-les-societes-ne-comptant-aucune-femme-cadre-superieure\"><em>Annexe 3\u2014Soci\u00e9t\u00e9s ne comptant aucune femme cadre sup\u00e9rieure\u00a0<\/em><\/a><\/li>\n<li><a href=\"\/knowledge\/enquete-catalyst-2012-annexe-4-la-representation-des-femmes-par-province-territoire\"><em>Annexe 4\u2014La repr\u00e9sentation des femmes par province\/territoire\u00a0<\/em><\/a><\/li>\n<li><a href=\"\/knowledge\/enquete-catalyst-2012-annexe-5-la-representation-des-femmes-par-industrie-scian\"><em>A<\/em><em><em>nnexe 5\u2014La repr\u00e9sentation des femmes par industrie SCIAN<\/em><\/em><\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ce rapport compte la proportion de femmes dans tous les postes de cadres sup\u00e9rieurs.<\/p>\n","protected":false},"author":9,"featured_media":0,"template":"","tags":[],"language":[],"campaign":[],"class_list":["post-4438","research_element","type-research_element","status-publish","hentry","topics-women-ceos","region-canada","research_type-report"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v23.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Enqu\u00eate Catalyst 2012 : Les femmes cadres sup\u00e9rieures et les femmes les mieux r\u00e9mun\u00e9r\u00e9es selon le classement Financial Post 500 (Rapport)<\/title>\n<meta name=\"description\" content=\"Ce rapport compte la proportion de femmes dans tous les postes de cadres sup\u00e9rieurs.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enqu\u00eate Catalyst 2012 : Les femmes cadres sup\u00e9rieures et les femmes les mieux r\u00e9mun\u00e9r\u00e9es selon le classement Financial Post 500 (Rapport)\" \/>\n<meta property=\"og:description\" content=\"Ce rapport compte la proportion de femmes dans tous les postes de cadres sup\u00e9rieurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/\" \/>\n<meta property=\"og:site_name\" content=\"Catalyst\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/catalystinc\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-13T16:44:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/classic.catalyst.org\/wp-content\/uploads\/2019\/03\/Catalyst-Logo-1200x630.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CatalystInc\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/\",\"url\":\"https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/\",\"name\":\"Enqu\u00eate Catalyst 2012 : Les femmes cadres sup\u00e9rieures et les femmes les mieux r\u00e9mun\u00e9r\u00e9es selon le classement Financial Post 500 (Rapport)\",\"isPartOf\":{\"@id\":\"https:\/\/classic.catalyst.org\/fr\/#website\"},\"datePublished\":\"2013-02-19T05:00:00+00:00\",\"dateModified\":\"2023-04-13T16:44:29+00:00\",\"description\":\"Ce rapport compte la proportion de femmes dans tous les postes de cadres sup\u00e9rieurs.\",\"breadcrumb\":{\"@id\":\"https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/classic.catalyst.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Research Elements\",\"item\":\"https:\/\/classic.catalyst.org\/fr\/research\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Enqu\u00eate Catalyst 2012 : Les femmes cadres sup\u00e9rieures et les femmes les mieux r\u00e9mun\u00e9r\u00e9es selon le classement Financial Post 500 (Rapport)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/classic.catalyst.org\/fr\/#website\",\"url\":\"https:\/\/classic.catalyst.org\/fr\/\",\"name\":\"Catalyst\",\"description\":\"Catalyst, a global nonprofit organization, helps build workplaces that work for women with preeminent thought leadership and actionable solutions.\",\"publisher\":{\"@id\":\"https:\/\/classic.catalyst.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/classic.catalyst.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/classic.catalyst.org\/fr\/#organization\",\"name\":\"Catalyst Inc.\",\"alternateName\":\"Catalyst\",\"url\":\"https:\/\/classic.catalyst.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/classic.catalyst.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.catalyst.org\/wp-content\/uploads\/2019\/03\/Catalyst-Logo-1200x630.png\",\"contentUrl\":\"https:\/\/www.catalyst.org\/wp-content\/uploads\/2019\/03\/Catalyst-Logo-1200x630.png\",\"width\":1200,\"height\":630,\"caption\":\"Catalyst Inc.\"},\"image\":{\"@id\":\"https:\/\/classic.catalyst.org\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/catalystinc\/\",\"https:\/\/x.com\/CatalystInc\",\"https:\/\/www.instagram.com\/catalystinc\/\",\"https:\/\/www.linkedin.com\/company\/catalystinc\/\",\"https:\/\/www.youtube.com\/user\/CatalystClips\",\"https:\/\/en.wikipedia.org\/wiki\/Catalyst_(nonprofit_organization)\"],\"description\":\"Catalyst is a global nonprofit supported by many of the world\u2019s most powerful CEOs and leading companies to help build workplaces that work for women.\",\"email\":\"info@catalyst.org\",\"telephone\":\"212-514-7600\",\"legalName\":\"Catalyst Inc.\",\"foundingDate\":\"1962-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Enqu\u00eate Catalyst 2012 : Les femmes cadres sup\u00e9rieures et les femmes les mieux r\u00e9mun\u00e9r\u00e9es selon le classement Financial Post 500 (Rapport)","description":"Ce rapport compte la proportion de femmes dans tous les postes de cadres sup\u00e9rieurs.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Enqu\u00eate Catalyst 2012 : Les femmes cadres sup\u00e9rieures et les femmes les mieux r\u00e9mun\u00e9r\u00e9es selon le classement Financial Post 500 (Rapport)","og_description":"Ce rapport compte la proportion de femmes dans tous les postes de cadres sup\u00e9rieurs.","og_url":"https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/","og_site_name":"Catalyst","article_publisher":"https:\/\/www.facebook.com\/catalystinc\/","article_modified_time":"2023-04-13T16:44:29+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/classic.catalyst.org\/wp-content\/uploads\/2019\/03\/Catalyst-Logo-1200x630.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@CatalystInc","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/","url":"https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/","name":"Enqu\u00eate Catalyst 2012 : Les femmes cadres sup\u00e9rieures et les femmes les mieux r\u00e9mun\u00e9r\u00e9es selon le classement Financial Post 500 (Rapport)","isPartOf":{"@id":"https:\/\/classic.catalyst.org\/fr\/#website"},"datePublished":"2013-02-19T05:00:00+00:00","dateModified":"2023-04-13T16:44:29+00:00","description":"Ce rapport compte la proportion de femmes dans tous les postes de cadres sup\u00e9rieurs.","breadcrumb":{"@id":"https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/classic.catalyst.org\/fr\/research\/enquete-catalyst-2012-les-femmes-cadres-superieures-et-les-femmes-les-mieux-remunerees-selon-le-classement-financial-post-500\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/classic.catalyst.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Research Elements","item":"https:\/\/classic.catalyst.org\/fr\/research\/"},{"@type":"ListItem","position":3,"name":"Enqu\u00eate Catalyst 2012 : Les femmes cadres sup\u00e9rieures et les femmes les mieux r\u00e9mun\u00e9r\u00e9es selon le classement Financial Post 500 (Rapport)"}]},{"@type":"WebSite","@id":"https:\/\/classic.catalyst.org\/fr\/#website","url":"https:\/\/classic.catalyst.org\/fr\/","name":"Catalyst","description":"Catalyst, a global nonprofit organization, helps build workplaces that work for women with preeminent thought leadership and actionable solutions.","publisher":{"@id":"https:\/\/classic.catalyst.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/classic.catalyst.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/classic.catalyst.org\/fr\/#organization","name":"Catalyst Inc.","alternateName":"Catalyst","url":"https:\/\/classic.catalyst.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/classic.catalyst.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.catalyst.org\/wp-content\/uploads\/2019\/03\/Catalyst-Logo-1200x630.png","contentUrl":"https:\/\/www.catalyst.org\/wp-content\/uploads\/2019\/03\/Catalyst-Logo-1200x630.png","width":1200,"height":630,"caption":"Catalyst Inc."},"image":{"@id":"https:\/\/classic.catalyst.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/catalystinc\/","https:\/\/x.com\/CatalystInc","https:\/\/www.instagram.com\/catalystinc\/","https:\/\/www.linkedin.com\/company\/catalystinc\/","https:\/\/www.youtube.com\/user\/CatalystClips","https:\/\/en.wikipedia.org\/wiki\/Catalyst_(nonprofit_organization)"],"description":"Catalyst is a global nonprofit supported by many of the world\u2019s most powerful CEOs and leading companies to help build workplaces that work for women.","email":"info@catalyst.org","telephone":"212-514-7600","legalName":"Catalyst Inc.","foundingDate":"1962-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/classic.catalyst.org\/fr\/wp-json\/wp\/v2\/research_element\/4438","targetHints":{"allow":["GET","POST","PUT","PATCH","DELETE"]}}],"collection":[{"href":"https:\/\/classic.catalyst.org\/fr\/wp-json\/wp\/v2\/research_element"}],"about":[{"href":"https:\/\/classic.catalyst.org\/fr\/wp-json\/wp\/v2\/types\/research_element"}],"author":[{"embeddable":true,"href":"https:\/\/classic.catalyst.org\/fr\/wp-json\/wp\/v2\/users\/9"}],"wp:attachment":[{"href":"https:\/\/classic.catalyst.org\/fr\/wp-json\/wp\/v2\/media?parent=4438"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/classic.catalyst.org\/fr\/wp-json\/wp\/v2\/tags?post=4438"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/classic.catalyst.org\/fr\/wp-json\/wp\/v2\/language?post=4438"},{"taxonomy":"campaign","embeddable":true,"href":"https:\/\/classic.catalyst.org\/fr\/wp-json\/wp\/v2\/campaign?post=4438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}